{"id":2632,"date":"2018-10-02T23:49:12","date_gmt":"2018-10-02T23:49:12","guid":{"rendered":"https:\/\/integralsomaticpsychology.com\/?p=2632"},"modified":"2020-03-24T09:12:55","modified_gmt":"2020-03-24T09:12:55","slug":"comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo","status":"publish","type":"post","link":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/","title":{"rendered":"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell&#8217;Atteggiamento, Del Sostegno e Dell&#8217;Integrazione Nel Corpo"},"content":{"rendered":"<p>L\u2019articolo propone una definizione di tolleranza emotiva, presenta tre importanti fattori che la guidano e le implicazioni per migliorare il lavoro con le emozioni in tutte le modalit\u00e0 terapeutiche.<\/p>\n<h2>Che cos\u2019\u00e8 la tolleranza emotiva? Perch\u00e9 \u00e8 importante?<\/h2>\n<p>Il dott. Robert Stolorow, co-autore di molti libri sull&#8217;approccio intersoggettivo alla psicoanalisi e dal quale sono stato abbastanza fortunato da ottenere supervisione durante i miei studi di dottorato, ha spesso puntualizzato che il compito principale della terapia dovrebbe essere la costruzione, da parte dei clienti, di una maggiore capacit\u00e0 di tolleranza emotiva. Il suo ragionamento \u00e8 il seguente: le persone di solito sviluppano sintomi dalla loro incapacit\u00e0 di tollerare le risposte emozionali alle situazioni. Generalmente il modo in cui i terapisti assistono i loro clienti \u00e8 quello di aiutarli ad affrontarle e ad elaborarle. Possiamo aspettarci che i nostri clienti rimarranno resilienti (o non svilupperanno sintomi) in futuro, solo quando, durante lo svolgersi della terapia, si trovano di fronte ad esperienze simili e sviluppano una maggiore capacit\u00e0 di tollerare esperienze emotive cos\u00ec difficili. \u00c8 importante notare che sia la psicologia junghiana che l&#8217;Advaita Vedanta sottolineano l&#8217;importanza di costruire una maggiore capacit\u00e0 di sviluppare gli opposti nell&#8217;esperienza umana, per la crescita personale e spirituale.<\/p>\n<p>La tolleranza emotiva non pu\u00f2 essere definita senza specificare una persona, un&#8217;emozione o una situazione. La capacit\u00e0 di provare e tollerare un&#8217;emozione varia da individuo a individuo. L\u2019abilit\u00e0 di un individuo di tollerare un&#8217;emozione dipende dall&#8217;emozione stessa, una persona potrebbe avere una capacit\u00e0 maggiore per un&#8217;emozione rispetto ad un&#8217;altra. Inoltre l\u2019abilit\u00e0 di un individuo di tollerare la stessa emozione varia sia nel tempo che a seconda della situazione. Ai fini di questo articolo, possiamo dire che una persona, in una determinata situazione, ha tolleranza per un&#8217;emozione se non si forma nessun sintomo quando la persona ha quell&#8217;emozione come reazione a quella situazione.<\/p>\n<h3>Quali fattori determinano la tolleranza emotiva di una persona?<\/h3>\n<ol>\n<li>Sostegno emotivo: il sostegno che si ha per un&#8217;emozione \u00e8 forse il fattore pi\u00f9 importante nel determinare la capacit\u00e0 di una persona di percepire e tollerare un\u2019emozione. Pu\u00f2 essere sotto forma di sostegno da parte di altri nel presente, oppure pu\u00f2 essere sotto forma di sostegno da parte di altri nel passato, che \u00e8 stato interiorizzato dall&#8217;individuo.<\/li>\n<li>Atteggiamenti nei confronti delle emozioni: l&#8217;atteggiamento di una persona nei confronti di un&#8217;emozione \u00e8 un fattore importante nel determinare la capacit\u00e0 della persona di percepire e tollerare un&#8217;emozione. Ci pu\u00f2 essere un certo numero di questi atteggiamenti. Ad esempio, alcune persone resistono alle emozioni spiacevoli perch\u00e9 credono che non sia sano soffermarsi su di esse. Alcuni credono che gli uomini non dovrebbero mostrare alcuna vulnerabilit\u00e0 e le donne non dovrebbero provare rabbia. Alcune persone non capiscono che le emozioni spiacevoli sono intrinsecamente difficili da sperimentare perch\u00e9 sono stati di stress e disorganizzazione nel cervello e nel corpo; ed \u00e8 necessario scavalcare la resistenza innata che si ha verso le emozioni spiacevoli per sperimentarle ed elaborarle. Si noti che i due fattori discussi finora sono correlati tra loro. Pi\u00f9 si ha sostegno per un&#8217;emozione, pi\u00f9 probabilmente ci sar\u00e0 un\u2019attitudine verso questa emozione. Pi\u00f9 una persona conosce il ruolo dell&#8217;emozione in relazione alla salute fisica e mentale, pi\u00f9 \u00e8 probabile che l&#8217;atteggiamento della persona sia funzionale nei confronti dell&#8217;esperienza emotiva.<\/li>\n<li>Integrazione dell&#8217;emozione nel corpo: pi\u00f9 un&#8217;emozione \u00e8 integrata nella maggior parte possibile del corpo, pi\u00f9 \u00e8 facile sperimentare e tollerare l&#8217;emozione. Con due braccia, invece che con una, \u00e8 pi\u00f9 facile sollevare non solo un carico maggiore, ma anche con maggiore facilit\u00e0. Per una spiegazione pi\u00f9 scientifica sul ruolo dell&#8217;integrazione della tolleranza emotiva basata sui risultati della fisiologia delle emozioni e dell&#8217;autoregolazione, vi invito a leggere il documento <a href=\"https:\/\/integralsomaticpsychology.com\/it\/come-migliorare-i-risultati-in-tutte-le-terapie-attraverso-lintegrazione-delle-emozioni-nel-corpo\/\"><em>Come<\/em>\u00a0<em>Migliorare i risultati in tutte le terapie attraverso l&#8217;integrazione delle emozioni nel corpo<\/em>.<\/a> I tre fattori, il sostegno, l&#8217;atteggiamento e l&#8217;integrazione nel corpo sono correlati l&#8217;un l&#8217;altro. Pi\u00f9 favorevoli sono le attitudini e maggiore \u00e8 il sostegno esterno per un&#8217;emozione, pi\u00f9 facile potrebbe essere integrare l&#8217;emozione nel corpo.<\/li>\n<\/ol>\n<h3>La relazione tra tolleranza emotiva ed espansione delle emozioni nel corpo<\/h3>\n<p>La relazione tra le capacit\u00e0 verso un&#8217;emozione e questi tre fattori \u00e8 rappresentata nello schema seguente:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-2637\" src=\"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/10\/Integral-Somatic-Psychology-Affect-Tolerance-Graph-It.jpg\" alt=\"Integral Sometic Psychology Affect Tolerance Graph\" width=\"750\" height=\"492\" srcset=\"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/10\/Integral-Somatic-Psychology-Affect-Tolerance-Graph-It.jpg 750w, https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/10\/Integral-Somatic-Psychology-Affect-Tolerance-Graph-It-600x394.jpg 600w, https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/10\/Integral-Somatic-Psychology-Affect-Tolerance-Graph-It-300x197.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Le esperienze emotive possono essere caratterizzate dal livello di emozione e dal livello di intensit\u00e0 (difficolt\u00e0). Una persona potrebbe trovare anche livelli bassi di esperienza emotiva estremamente intensa (difficile) da tollerare, come nel caso della linea 1. Oppure una persona potrebbe trovare livelli di emozione ancora pi\u00f9 intensi (intensi) da sperimentare e tollerare, come lungo la linea 3. Quanto pi\u00f9 c\u2019\u00e8 sostegno per un&#8217;emozione in una situazione, migliore \u00e8 l&#8217;atteggiamento verso questa stessa, e quanto maggiormente l\u2019emozione \u00e8 integrata (o espansa) nel corpo, tanto pi\u00f9 piatto sar\u00e0 il profilo di tolleranza emotiva di un individuo, come lungo la linea 3. Cio\u00e8, \u00e8 probabile che la persona provi tutti i livelli di emozione con livelli pi\u00f9 bassi di intensit\u00e0 (difficolt\u00e0). Oppure, mantenendo costante il livello di sostegno emotivo e l&#8217;atteggiamento verso un&#8217;emozione fissa, \u00e8 possibile fare il profilo di tolleranza emotiva di un individuo per un&#8217;emozione pi\u00f9 piatta o pi\u00f9 suscettibile aumentando l&#8217;area del corpo che \u00e8 coinvolta nell&#8217;emozione. Un livello pi\u00f9 alto di emozione, quando distribuito in modo pi\u00f9 uniforme nel corpo, \u00e8 meno probabile che sia cos\u00ec intenso o difficile da percepire e tollerare per qualsiasi parte del corpo coinvolta nell&#8217;esperienza di quell&#8217;emozione, per far innescare i sintomi.<\/p>\n<p>Migliorare la tolleranza emotiva di una persona pu\u00f2 risolvere i sintomi e aumentare la capacit\u00e0 di recupero in modo che i sintomi non si formino in futuro. Fornendo sostegno emotivo e migliorando gli atteggiamenti della persona nei confronti di un&#8217;emozione, cose che i terapisti fanno sempre, aiutano i clienti facendo crescere la loro capacit\u00e0 di tollerare l&#8217;emozione. Tuttavia, non molti terapisti lavorano con il corpo in relazione alle emozioni. Inoltre anche quelli che lavorano con il corpo in relazione alle emozioni, raramente cercano di espandere le emozioni nel corpo come modo per sviluppare una maggiore capacit\u00e0 di tollerarle. Pertanto, lo scopo di migliorare la tolleranza emotiva attraverso l&#8217;aumento dell\u2019integrazione \u00e8 rilevante in tutte le modalit\u00e0 terapeutiche, sia che siano gi\u00e0 orientate al corpo o meno.<\/p>\n<p>Si \u00e8 scoperto che il beneficio dell&#8217;integrazione emotiva non \u00e8 limitato solo a migliori esiti emotivi. Per capire come una maggiore capacit\u00e0 di tolleranza emotiva, attraverso l&#8217;integrazione dell&#8217;emozione nel corpo, possa anche migliorare i risultati cognitivi, comportamentali, fisici, energetici, relazionali e spirituali in tutte le terapie, leggi il documento <em><a href=\"https:\/\/integralsomaticpsychology.com\/it\/implicazioni-per-migliorare-i-risultati-in-tutte-le-terapie\/\">La scienza dell\u2019Embodied Cognition (Cognizione Incarnata) e dell&#8217;Emozione Enattiva: implicazioni per migliorare i risultati in tutte le terapie<\/a><\/em>. Per leggere qualcosa su Integral Somatic Psychology\u2122 (ISP\u2122), una modalit\u00e0 complementare sviluppata per migliorare gli esiti in tutte le terapie attraverso l&#8217;integrazione delle emozioni nel corpo, si prega di leggere il documento <a href=\"https:\/\/integralsomaticpsychology.com\/it\/cose-integral-somatic-psychology-una-conversazione-con-raja-selvam\/\"><em>Cos&#8217;\u00e8 l&#8217;Integral Somatic Psychology (ISP)? Una conversazione con Raja Selvam, PhD<\/em><\/a>. Per saperne di pi\u00f9 su come facilitare la percezione di una vasta gamma di esperienze emotive, incluse le emozioni senso-motorie sempre presenti, e spesso trascurate, in modo che si possa sempre trovare un&#8217;emozione con cui lavorare, in qualsiasi sessione, in qualsiasi modalit\u00e0 terapeutica, su come identificare e lavorare con le difese psicologiche, fisiche ed energetiche contro le esperienze emotive, inoltre come espandere il corpo e l&#8217;energia per espandere l&#8217;esperienza delle emozioni nel corpo in modo tale che l&#8217;emozione, il corpo e l&#8217;energia rimangano regolati e si sviluppi una maggiore capacit\u00e0 di tolleranza emotiva. Vi invito a visitare la pagina del programma di training all&#8217;indirizzo <a href=\"https:\/\/integralsomaticpsychology.com\">integralsomaticpsychology.com<\/a>, per trovare un corso o un seminario ISP vicino a voi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019articolo propone una definizione di tolleranza emotiva, presenta tre importanti fattori che la guidano e le implicazioni per migliorare il lavoro con le emozioni in tutte le modalit\u00e0 terapeutiche. Che cos\u2019\u00e8 la tolleranza emotiva? Perch\u00e9 \u00e8 importante? Il dott. Robert Stolorow, co-autore di molti libri sull&#8217;approccio intersoggettivo alla psicoanalisi e dal quale sono stato abbastanza [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"content-sidebar","footnotes":""},"categories":[47],"tags":[],"class_list":["post-2632","post","type-post","status-publish","format-standard","has-post-thumbnail","category-emozioni","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell&#039;Atteggiamento, Del Sostegno e Dell&#039;Integrazione Nel Corpo<\/title>\n<meta name=\"description\" content=\"L\u2019articolo propone una definizione di tolleranza emotiva, presenta tre importanti fattori che la guidano e le implicazioni per migliorare il lavoro con le\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell&#039;Atteggiamento, Del Sostegno e Dell&#039;Integrazione Nel Corpo\" \/>\n<meta property=\"og:description\" content=\"L\u2019articolo propone una definizione di tolleranza emotiva, presenta tre importanti fattori che la guidano e le implicazioni per migliorare il lavoro con le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/\" \/>\n<meta property=\"og:site_name\" content=\"ISP\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-02T23:49:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-24T09:12:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/09\/Affect-Tolerance-ISP-Blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raja Selvam, PhD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raja Selvam, PhD\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/\"},\"author\":{\"name\":\"Raja Selvam, PhD\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#\\\/schema\\\/person\\\/bddf9014a05428d7831a82f46831693c\"},\"headline\":\"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell&#8217;Atteggiamento, Del Sostegno e Dell&#8217;Integrazione Nel Corpo\",\"datePublished\":\"2018-10-02T23:49:12+00:00\",\"dateModified\":\"2020-03-24T09:12:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/\"},\"wordCount\":1288,\"image\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Affect-Tolerance-ISP-Blog.jpg\",\"articleSection\":[\"Emozioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/\",\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/\",\"name\":\"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell'Atteggiamento, Del Sostegno e Dell'Integrazione Nel Corpo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Affect-Tolerance-ISP-Blog.jpg\",\"datePublished\":\"2018-10-02T23:49:12+00:00\",\"dateModified\":\"2020-03-24T09:12:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#\\\/schema\\\/person\\\/bddf9014a05428d7831a82f46831693c\"},\"description\":\"L\u2019articolo propone una definizione di tolleranza emotiva, presenta tre importanti fattori che la guidano e le implicazioni per migliorare il lavoro con le\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Affect-Tolerance-ISP-Blog.jpg\",\"contentUrl\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Affect-Tolerance-ISP-Blog.jpg\",\"width\":750,\"height\":300,\"caption\":\"Couple in therapy showing lack of affect tolerance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell&#8217;Atteggiamento, Del Sostegno e Dell&#8217;Integrazione Nel Corpo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/\",\"name\":\"ISP\",\"description\":\"Integral Somatic Psychology\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#\\\/schema\\\/person\\\/bddf9014a05428d7831a82f46831693c\",\"name\":\"Raja Selvam, PhD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-raja-selvam-phd-96x96.png\",\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-raja-selvam-phd-96x96.png\",\"contentUrl\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-raja-selvam-phd-96x96.png\",\"caption\":\"Raja Selvam, PhD\"},\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/author\\\/amsolutions\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell'Atteggiamento, Del Sostegno e Dell'Integrazione Nel Corpo","description":"L\u2019articolo propone una definizione di tolleranza emotiva, presenta tre importanti fattori che la guidano e le implicazioni per migliorare il lavoro con le","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell'Atteggiamento, Del Sostegno e Dell'Integrazione Nel Corpo","og_description":"L\u2019articolo propone una definizione di tolleranza emotiva, presenta tre importanti fattori che la guidano e le implicazioni per migliorare il lavoro con le","og_url":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/","og_site_name":"ISP","article_published_time":"2018-10-02T23:49:12+00:00","article_modified_time":"2020-03-24T09:12:55+00:00","og_image":[{"width":750,"height":300,"url":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/09\/Affect-Tolerance-ISP-Blog.jpg","type":"image\/jpeg"}],"author":"Raja Selvam, PhD","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Raja Selvam, PhD","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/#article","isPartOf":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/"},"author":{"name":"Raja Selvam, PhD","@id":"https:\/\/integralsomaticpsychology.com\/it\/#\/schema\/person\/bddf9014a05428d7831a82f46831693c"},"headline":"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell&#8217;Atteggiamento, Del Sostegno e Dell&#8217;Integrazione Nel Corpo","datePublished":"2018-10-02T23:49:12+00:00","dateModified":"2020-03-24T09:12:55+00:00","mainEntityOfPage":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/"},"wordCount":1288,"image":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/#primaryimage"},"thumbnailUrl":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/09\/Affect-Tolerance-ISP-Blog.jpg","articleSection":["Emozioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/","url":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/","name":"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell'Atteggiamento, Del Sostegno e Dell'Integrazione Nel Corpo","isPartOf":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/#primaryimage"},"image":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/#primaryimage"},"thumbnailUrl":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/09\/Affect-Tolerance-ISP-Blog.jpg","datePublished":"2018-10-02T23:49:12+00:00","dateModified":"2020-03-24T09:12:55+00:00","author":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/#\/schema\/person\/bddf9014a05428d7831a82f46831693c"},"description":"L\u2019articolo propone una definizione di tolleranza emotiva, presenta tre importanti fattori che la guidano e le implicazioni per migliorare il lavoro con le","breadcrumb":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/#primaryimage","url":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/09\/Affect-Tolerance-ISP-Blog.jpg","contentUrl":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/09\/Affect-Tolerance-ISP-Blog.jpg","width":750,"height":300,"caption":"Couple in therapy showing lack of affect tolerance"},{"@type":"BreadcrumbList","@id":"https:\/\/integralsomaticpsychology.com\/it\/comprendere-e-migliorare-la-tolleranza-emotiva-il-ruolo-dellatteggiamento-del-sostegno-e-dellintegrazione-nel-corpo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/integralsomaticpsychology.com\/"},{"@type":"ListItem","position":2,"name":"Comprendere e Migliorare La Tolleranza Emotiva: Il Ruolo Dell&#8217;Atteggiamento, Del Sostegno e Dell&#8217;Integrazione Nel Corpo"}]},{"@type":"WebSite","@id":"https:\/\/integralsomaticpsychology.com\/it\/#website","url":"https:\/\/integralsomaticpsychology.com\/it\/","name":"ISP","description":"Integral Somatic Psychology","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/integralsomaticpsychology.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/integralsomaticpsychology.com\/it\/#\/schema\/person\/bddf9014a05428d7831a82f46831693c","name":"Raja Selvam, PhD","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2023\/10\/cropped-raja-selvam-phd-96x96.png","url":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2023\/10\/cropped-raja-selvam-phd-96x96.png","contentUrl":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2023\/10\/cropped-raja-selvam-phd-96x96.png","caption":"Raja Selvam, PhD"},"url":"https:\/\/integralsomaticpsychology.com\/it\/author\/amsolutions\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/posts\/2632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/comments?post=2632"}],"version-history":[{"count":0,"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/posts\/2632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/media\/2611"}],"wp:attachment":[{"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/media?parent=2632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/categories?post=2632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/it\/wp-json\/wp\/v2\/tags?post=2632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}