{"id":9744,"date":"2024-05-16T08:25:42","date_gmt":"2024-05-16T08:25:42","guid":{"rendered":"https:\/\/integralsomaticpsychology.com\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/"},"modified":"2024-05-16T08:30:53","modified_gmt":"2024-05-16T08:30:53","slug":"la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias","status":"publish","type":"post","link":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/","title":{"rendered":"La ciencia de la cognici\u00f3n corporizada y la emoci\u00f3n enactiva: Implicaciones para mejorar los resultados en todas las terapias"},"content":{"rendered":"<p><b>Resumen:<\/b> La investigaci\u00f3n que cambia paradigmas en la neurociencia cognitiva en \u00e1reas llamadas cognici\u00f3n corporizada y embebida, as\u00ed como la investigaci\u00f3n igualmente importante sobre lo que se denominan enfoques corporizados y enactivos de la emoci\u00f3n, realizada en universidades en los \u00faltimos veinte a\u00f1os, ha modificado mucho nuestra comprensi\u00f3n de la cognici\u00f3n, la emoci\u00f3n, la conducta, c\u00f3mo est\u00e1n estrechamente relacionadas entre s\u00ed en el cerebro y c\u00f3mo se involucran e interact\u00faan entre s\u00ed en el cuerpo. Estos descubrimientos ofrecen perspectivas radicalmente novedosas que cuestionan la eficacia de las formas t\u00edpicas en que las psicoterapias (incluidas las orientadas al cuerpo) trabajan con estos fen\u00f3menos. Asimismo, sugieren nuevos m\u00e9todos para mejorar notablemente los resultados cognitivos, emocionales y conductuales, as\u00ed como los f\u00edsicos, energ\u00e9ticos, relacionales y espirituales en todas las modalidades terap\u00e9uticas. Este es el asunto sobre el que versa este breve art\u00edculo.<\/p>\n<h3>La relaci\u00f3n entre cognici\u00f3n y cuerpo<\/h3>\n<p>Lo que se incluye en la definici\u00f3n de cognici\u00f3n var\u00eda seg\u00fan la tradici\u00f3n investigadora. Cuando se define en sentido amplio, abarca la atenci\u00f3n, el enfoque, la percepci\u00f3n, la simbolizaci\u00f3n, el lenguaje, la categorizaci\u00f3n, la contextualizaci\u00f3n, la asociaci\u00f3n, la imaginaci\u00f3n, la memoria, el recuerdo, la l\u00f3gica, la inferencia y el significado. Esta es la definici\u00f3n que se emplea en este art\u00edculo. De acuerdo con las teor\u00edas cada vez m\u00e1s basadas en la evidencia de los enfoques corporizados y embebidos de la cognici\u00f3n (Colombetti, 2014) y la filosof\u00eda corporizada de la mente (Johnson, 2017), todos estos aspectos de la cognici\u00f3n ata\u00f1en no solo al cerebro, sino tambi\u00e9n a todo el cuerpo a medida que interact\u00faa con (el cuerpo de) su entorno.<\/p>\n<p>Diversos experimentos han establecido que, tanto el aprendizaje de fen\u00f3menos simples como el reconocimiento de letras en jardines de infancia, como el aprendizaje de fen\u00f3menos complejos como la ley f\u00edsica de la inercia en la universidad, mejora notablemente cuando el cuerpo y el entorno participan m\u00e1s en el proceso de aprendizaje (Beilock, 2017). Por lo tanto, cualquier aspecto de la cognici\u00f3n que empiece por la atenci\u00f3n no puede entenderse estudiando el cerebro \u00fanicamente. Trabajar con el cuerpo en relaci\u00f3n con su entorno, adem\u00e1s del trabajo habitual con el cerebro, mejorar\u00eda todos los resultados cognitivos arriba mencionados.<\/p>\n<p>Hallazgos anteriores de las psicoterapias orientadas al cuerpo vinculan la cognici\u00f3n con el cuerpo. Por ejemplo, Eugene Gendlin (1998), fil\u00f3sofo reconvertido en psic\u00f3logo y fundador de la Terapia de Focusing, demostr\u00f3, mediante experimentos realizados en la Universidad de Chicago, que las personas que integraban m\u00ednimamente al cuerpo siendo conscientes de las sensaciones corporales de vez en cuando resolv\u00edan mejor los problemas cognitivos que las que no lo hac\u00edan. El An\u00e1lisis Bodynamic (Marcher y Fisch, 2010), un sistema dan\u00e9s de psicoterapia corporal con un mapa de las funciones psicol\u00f3gicas del sistema muscular obtenido emp\u00edricamente, ha identificado varios m\u00fasculos en diferentes partes del cuerpo, como los flexores de los dedos de las manos y los pies, que median el procesamiento cognitivo en el cerebro. Lo que la investigaci\u00f3n de la cognici\u00f3n corporizada ha podido ofrecer \u00faltimamente es la ciencia y la evidencia que ni la terapia de Focusing ni el An\u00e1lisis Bodynamic pudieron ofrecer en su momento acerca de la importancia del cuerpo en la comprensi\u00f3n y el trabajo con la cognici\u00f3n.<\/p>\n<h3>La relaci\u00f3n entre cognici\u00f3n y emoci\u00f3n<\/h3>\n<p>Varios estudios recientes sobre la cognici\u00f3n corporizada basados en la fisiolog\u00eda del cerebro (Johnson, 2007; Colombetti y Thompson, 2008) han demostrado que todos los aspectos de la cognici\u00f3n (empezando por las decisiones iniciales que determinan a qu\u00e9 aspectos del entorno prestamos atenci\u00f3n incluso antes de que nuestros sentidos perciban el entorno) est\u00e1n mediados, influidos o incluso iniciados por el afecto (en este art\u00edculo, los t\u00e9rminos afecto, emoci\u00f3n y sentimiento se emplean indistintamente para referirse a lo mismo). Recientes pruebas neurol\u00f3gicas demuestran que, durante tareas experimentales cognitivas, o bien se activan simult\u00e1neamente los circuitos cerebrales cognitivos y afectivos, o bien los circuitos afectivos se activan antes que los cognitivos. Tambi\u00e9n existen nuevas evidencias de que las \u00e1reas cerebrales activadas durante tareas cognitivas y afectivas se solapan.<\/p>\n<p>La evidencia del papel causal del afecto en la cognici\u00f3n proviene del hallazgo de que hay m\u00e1s v\u00edas que van desde las \u00e1reas cerebrales que tienen que ver con el afecto a las \u00e1reas que tienen que ver con la cognici\u00f3n y la conducta que a la inversa (Barrett, 2017). Mientras que las primeras investigaciones presentadas por Damasio (1994) mostraban la importancia de la emoci\u00f3n en la comprensi\u00f3n y el trabajo con la conducta, la investigaci\u00f3n actual sobre la cognici\u00f3n corporizada y embebida, as\u00ed como la de los enfoques corporizados y enactivos de la emoci\u00f3n, muestran la importancia de la emoci\u00f3n y su corporizaci\u00f3n en la comprensi\u00f3n y el trabajo con la cognici\u00f3n.<\/p>\n<h3>La relaci\u00f3n entre cognici\u00f3n, emoci\u00f3n y cuerpo<\/h3>\n<p>El papel de todo el cuerpo en la generaci\u00f3n de experiencias emocionales est\u00e1 bien documentado (Pert, 1999; Damasio, 2003; Barrett, 2017). Sin embargo, solo recientemente se ha empleado la participaci\u00f3n del cuerpo en la emoci\u00f3n para establecer la conexi\u00f3n entre la cognici\u00f3n y el cuerpo. Es decir, la emoci\u00f3n proporciona un posible v\u00ednculo entre la cognici\u00f3n y el cuerpo (y la conducta proporciona otro posible v\u00ednculo entre ellos). En los experimentos en los que los m\u00fasculos faciales, que se sabe desempe\u00f1an un papel importante en la emoci\u00f3n, quedan impedidos de una forma u otra, los procesos cognitivos como la impronta y el recuerdo de las emociones y sus contextos se ven significativamente comprometidos (Niedenthal, 2007).<\/p>\n<p>El hallazgo de todo el cuerpo est\u00e1 implicado en las experiencias emocionales nos informa de que nuestra comprensi\u00f3n de las emociones ser\u00eda m\u00e1s completa y nuestro trabajo con las emociones m\u00e1s eficaz si se incluyera una mayor parte del cuerpo. Los descubrimientos como el de Niedenthal, que a\u00fanan la emoci\u00f3n, la cognici\u00f3n y el cuerpo, nos revelan que, para mejorar los resultados cognitivos, necesitamos trabajar con el cuerpo espec\u00edficamente en relaci\u00f3n con las emociones y su disponibilidad. Asimismo, nos indican que la cognici\u00f3n se resentir\u00eda si el cuerpo se viera comprometido de forma que su papel en la emoci\u00f3n se viera disminuido.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/02\/embodied-cognition-emotion-ISP-blog-raja-selvam-phd.jpg\" \/><\/p>\n<h3>La relaci\u00f3n entre emoci\u00f3n, conducta y cuerpo<\/h3>\n<p>Las investigaciones anteriores sobre la emoci\u00f3n que se centran en el cerebro (Damasio, 1999) han encontrado pruebas significativas de que las emociones, en contra de la creencia convencional de que son irracionales e interfieren con la racionalidad de la cognici\u00f3n, mejoran la adecuaci\u00f3n de la conducta de una persona al mejorar la creaci\u00f3n de alternativas conductuales y la elecci\u00f3n de la mejor forma de actuar en cualquier situaci\u00f3n. Estos hallazgos tambi\u00e9n ofrecen pruebas indirectas de que las personas son m\u00e1s capaces de comprender los contextos en los que se encuentran (es decir, captan mejor las situaciones desde el punto de vista cognitivo), actuando de forma m\u00e1s apropiada cuando tienen acceso a las emociones que cuando no las tienen. El papel del cuerpo en la conducta, la expresi\u00f3n y la acci\u00f3n es evidente. Damasio ha observado que la emoci\u00f3n tiene que producirse a trav\u00e9s del cuerpo como una evaluaci\u00f3n antes de que se tome una decisi\u00f3n conductual.<\/p>\n<h3>Las relaciones entre cognici\u00f3n, emoci\u00f3n y conducta<\/h3>\n<p>La investigaci\u00f3n demuestra que la emoci\u00f3n y la cognici\u00f3n est\u00e1n tan \u00edntimamente entrelazadas en el cerebro y el cuerpo que son pr\u00e1cticamente inseparables al surgir en el organismo, aunque en la experiencia puedan diferenciarse en cierto modo como fen\u00f3menos separados. En cada momento, el estado afectivo del organismo dirige todos los aspectos de su cognici\u00f3n, empezando por aquello a lo que el organismo presta atenci\u00f3n en su entorno. De hecho, Duncan y Barrett (2007) llegan a afirmar que el afecto es una forma de cognici\u00f3n.<\/p>\n<p>Se pueden hacer observaciones similares sobre la relaci\u00f3n entre la conducta y la emoci\u00f3n. En todo momento, un organismo se encuentra en un estado afectivo b\u00e1sico definido en t\u00e9rminos de valencia (buena o mala) y activaci\u00f3n (alta o baja), y cada impulso conductual tiene como base o fuerza motriz al menos este estado afectivo b\u00e1sico. Esto hace que el afecto y la conducta sean tambi\u00e9n inseparables cuando surgen en el cerebro o en el cuerpo, aunque puedan diferenciarse en cierto modo en la experiencia como fen\u00f3menos separados. La descripci\u00f3n de la emoci\u00f3n como energ\u00eda en movimiento y el reciente \u2018enfoque enactivo\u2019 de la emoci\u00f3n de Hufendiek (2016) son intentos de abordar la inseparabilidad de la conducta y la emoci\u00f3n.<\/p>\n<p>La investigaci\u00f3n sobre la cognici\u00f3n corporizada establece la relaci\u00f3n entre la cognici\u00f3n y el cuerpo mediante la relaci\u00f3n entre la cognici\u00f3n y la conducta. Toda conducta, expresi\u00f3n y acci\u00f3n involucran al cuerpo. Ya hemos visto que el aprendizaje de fen\u00f3menos simples y complejos se ve facilitado o inhibido por la conducta del cuerpo. En cuanto a la inseparabilidad entre la cognici\u00f3n y la conducta en la fisiolog\u00eda, incluso la percepci\u00f3n, un acto cognitivo, se considera ahora una acci\u00f3n (conducta) y, por tanto, es pr\u00e1cticamente inseparable de ella (Creem-Regher y Kunz, 2010). Asimismo, la intencionalidad en una conducta es un significado (cognici\u00f3n) y es inseparable del acto.<\/p>\n<p>La inseparabilidad del afecto y la cognici\u00f3n, del afecto y la conducta, y de la cognici\u00f3n y la conducta, as\u00ed como el papel primordial que desempe\u00f1a el afecto en la mediaci\u00f3n de la cognici\u00f3n y la conducta, hacen que los tres sean inseparables cuando surgen en el organismo, aunque puedan ser discernibles de alguna manera en la experiencia.<\/p>\n<h3>Implicaciones para la pr\u00e1ctica psicoterap\u00e9utica<\/h3>\n<p>Las psicoterapias tienden a especializarse en el trabajo con la cognici\u00f3n, el afecto o la conducta, centr\u00e1ndose normalmente en uno m\u00e1s que en los otros dos. Dado que ahora sabemos que los tres son pr\u00e1cticamente inseparables, tiene sentido que todas estas terapias especializadas funcionen en mayor o menor medida porque el trabajo centrado en cualquiera de estos elementos repercutir\u00eda tambi\u00e9n en los otros dos. Sin embargo, para garantizar los mejores resultados posibles en la terapia, estos nuevos hallazgos sugieren que deber\u00edamos: 1) trabajar con la cognici\u00f3n, el afecto y la conducta en estrecha proximidad o asociaci\u00f3n entre s\u00ed e implicar la mayor parte posible del cuerpo, ya que ahora se sabe que los tres involucran a todo el cuerpo; 2) trabajar especialmente con el afecto, porque ahora se sabe que este desempe\u00f1a un papel primordial a la hora de influir o incluso iniciar la cognici\u00f3n y la conducta; y 3) trabajar con el afecto en relaci\u00f3n con la mayor parte posible del cuerpo, pues este es potencialmente un fen\u00f3meno corporal completo y sabemos, gracias a la psicoterapia corporal y la psiquiatr\u00eda, que el afecto abrumador e intolerable puede provocar defensas fisiol\u00f3gicas en el cerebro y el cuerpo que comprometen su disponibilidad para la cognici\u00f3n, el afecto y la conducta.<\/p>\n<p>Las dificultades emocionales son a menudo, si no siempre, la causa de la aparici\u00f3n defensas en la fisiolog\u00eda cerebral y corporal. La consiguiente reducci\u00f3n de la disponibilidad de informaci\u00f3n emocional en el organismo a causa de dichas defensas puede comprometer no solo los resultados en el \u00e1mbito afectivo, sino tambi\u00e9n en los \u00e1mbitos cognitivo y conductual, que ahora sabemos, gracias a investigaciones recientes, que dependen en gran medida del \u00e1mbito afectivo y son inseparables de \u00e9l. El apagado o cierre del cuerpo debido a las defensas fisiol\u00f3gicas contra las emociones tambi\u00e9n puede comprometer la cognici\u00f3n y la conducta, que ahora se sabe que dependen de todo el cuerpo de otras maneras que mediante la participaci\u00f3n del afecto.<\/p>\n<p>Cuanto mayor sea la disponibilidad de la informaci\u00f3n emocional en la mayor parte posible del cuerpo, cuanto m\u00e1s regulada est\u00e9, cuanto m\u00e1s soportable sea y durante un per\u00edodo de tiempo m\u00e1s largo (la definici\u00f3n de corporizaci\u00f3n emocional en la Psicolog\u00eda Som\u00e1tica Integral\u2122), m\u00e1s probabilidades hay de que el cuerpo est\u00e9 abierto y disponible para participar en procesos cognitivos, afectivos y conductuales; y mayor ser\u00e1 tambi\u00e9n la probabilidad de que mejoren los resultados cognitivos, afectivos y conductuales en todas las modalidades de terapia. En el art\u00edculo titulado <a href=\"https:\/\/integralsomaticpsychology.com\/improve-outcomes-therapies-embodiment-emotions-2\/\" target=\"_blank\" rel=\"noopener\">C\u00f3mo mejorar los resultados en todas las terapias mediante la corporizaci\u00f3n de las emociones<\/a>, los lectores podr\u00e1n informarse acerca la corporizaci\u00f3n emocional y c\u00f3mo esta puede mejorar los resultados en todas las modalidades terap\u00e9uticas. El art\u00edculo tambi\u00e9n analiza c\u00f3mo el trabajo actual con las emociones en la psicoterapia convencional, as\u00ed como las modalidades de psicoterapia orientadas al cuerpo, podr\u00eda ser deficiente debido a la falta de integraci\u00f3n de informaci\u00f3n relevante sobre la compleja fisiolog\u00eda de la cognici\u00f3n, la emoci\u00f3n y la conducta, tal y como se presenta en este art\u00edculo.<\/p>\n<p>Adem\u00e1s, los enfoques de psicoterapia corporal m\u00e1s recientes como la Experiencia Som\u00e1tica\u00ae (SETM), la Terapia de Focusing, la Psicoterapia Sensoriomotriz\u00ae (SP) y la Terapia de Reducci\u00f3n del Estr\u00e9s Basada en Mindfulness (MSBR) a menudo utilizan el rastreo detallado de las sensaciones corporales como herramienta para trabajar con el cuerpo. Refiero a los lectores al art\u00edculo <a href=\"https:\/\/integralsomaticpsychology.com\/how-to-avoid-destroying-emotions-when-tracking-body-sensations\/\" target=\"_blank\" rel=\"noopener\">C\u00f3mo evitar destruir las Emociones al rastrear las sensaciones corporales<\/a> en el que se explica c\u00f3mo el rastreo detallado de las sensaciones corporales, una herramienta efectiva y basada en la evidencia, puede a veces comprometer el trabajo con las experiencias emocionales complejas, la cognici\u00f3n y la conducta.<\/p>\n<h3>Qu\u00e9 es la Psicolog\u00eda Som\u00e1tica Integral\u2122 (PSI\u2122)<\/h3>\n<p>La <a href=\"https:\/\/integralsomaticpsychology.com\/what-is-integral-somatic-psychology\/\" target=\"_blank\" rel=\"noopener\">Psicolog\u00eda Som\u00e1tica Integral<\/a> (PSI) es la siguiente generaci\u00f3n en la evoluci\u00f3n de la psicoterapia corporal basada en los \u00faltimos descubrimientos de la neurociencia, la psicoterapia corporal, la f\u00edsica cu\u00e1ntica y la psicolog\u00eda energ\u00e9tica sobre la cognici\u00f3n, la emoci\u00f3n y la conducta, c\u00f3mo se relacionan entre s\u00ed en el cerebro y el cuerpo, c\u00f3mo pueden verse comprometidas por las defensas fisiol\u00f3gicas tanto en el cerebro como en el cuerpo, y c\u00f3mo se puede trabajar con dichas defensas para facilitar la corporizaci\u00f3n de las emociones de manera simple, efectiva y regulada, mejorando a\u00fan m\u00e1s los resultados cognitivos, afectivos y conductuales, as\u00ed como los f\u00edsicos, energ\u00e9ticos, relacionales y espirituales en todas las modalidades de terapia. Actualmente, la PSI se imparte en m\u00e1s de una docena de pa\u00edses. Para matricularse, no se requiere formaci\u00f3n previa en psicoterapia de orientaci\u00f3n corporal. El art\u00edculo <a href=\"https:\/\/integralsomaticpsychology.com\/a-conversation-with-raja-selvam\/\" target=\"_blank\" rel=\"noopener\">Qu\u00e9 es la Psicolog\u00eda Som\u00e1tica Integral. Una conversaci\u00f3n con Raja Selvam<\/a> presenta la teor\u00eda y la pr\u00e1ctica de la ISP en un formato de entrevista sencillo y f\u00e1cil de leer. Para m\u00e1s informaci\u00f3n sobre este enfoque, sus aplicaciones y su programa de formaci\u00f3n internacional, visita <a href=\"https:\/\/integralsomaticpsychology.com\" target=\"_blank\" rel=\"noopener\">www.integralsomaticpsychology.com<\/a><\/p>\n<h3>Bibliograf\u00eda<\/h3>\n<p>Barrett, L. F. (2017). How emotions are made: The secret life of the brain. Houghton Mifflin Harcourt: Boston and New York.<\/p>\n<p>Beilock, S. (2017). How the body knows its mind: The surprising power of the physical environment to influence the how you think and feel. New York, NY: Atria Books, Simon &amp; Schuster, Inc.<\/p>\n<p>Colombetti, G. &amp; Thompson, E. (2008). The feeling body: Towards an enactive approach to emotion. In Overton W. F., Muller U., &amp; Newman J. L. (Eds.), Developmental Perspectives on Embodiment and Consciousness (pp. 45-68), New York: Lawrence Erlbaum Associates.<\/p>\n<p>Colombetti, G. (2014). The feeling body: Affective science meets the enactive mind. The MIT Press: Boston, Massachusetts &amp; London, UK.<\/p>\n<p>Creem-Regehr, S. H. and Kunz, B. R. (2010). Perception and action. WIREs Cogn Sci, 1: 800\u2013810. doi:10.1002\/wcs.82<\/p>\n<p>Damasio, A. (1994). Descartes\u2019 error: Emotion, reason, and the human brain. New York: Penguin Books.<\/p>\n<p>Damasio, A. (2003). Looking for Spinoza: Joy, sorrow, and the feeling brain. Orlando, FL: Harcourt, Inc.<\/p>\n<p>Duncan, S. and Barrett, L. F. (2007). Affect is a form of cognition: A neurobiological analysis. Cognition and Emotion, V 21(6), 1184 \u2013 1211. Doi.org\/10.1080\/02699930701437931<\/p>\n<p>Gendlin, E. T. (1998). Focusing-oriented psychotherapy: A manual of the experiential method. The Guildford Press: New York, New York.<\/p>\n<p>Johnson, M. (2007). Meaning of the body: Aesthetics of human understanding. The University of Chicago Press: Chicago, Illinois.<\/p>\n<p>Johnson, M. (2017). Embodied mind, meaning, and reason: How our bodies give rise to understanding. The University of Chicago Press: Chicago, Illinois.<\/p>\n<p>Hufendiek, R. (2016). Embodied emotions: A naturalistic approach to a normative phenomenon. Routledge Taylor &amp; Francis Group: New York and London.<\/p>\n<p>Marcher, L. &amp; Fisch, S. (2010). Body encyclopedia: A guide to the psychological functions of the muscular system. Berkeley, CA: North Atlantic Books.<\/p>\n<p>Niedenthal, P. (2007). Embodying emotion. Science (316), 1002-1005.<\/p>\n<p>Pert, C. (1999). Molecules of Emotion: The science behind mind-body medicine. New York: Simon &amp; Schuster, Inc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumen: La investigaci\u00f3n que cambia paradigmas en la neurociencia cognitiva en \u00e1reas llamadas cognici\u00f3n corporizada y embebida, as\u00ed como la investigaci\u00f3n igualmente importante sobre lo que se denominan enfoques corporizados y enactivos de la emoci\u00f3n, realizada en universidades en los \u00faltimos veinte a\u00f1os, ha modificado mucho nuestra comprensi\u00f3n de la cognici\u00f3n, la emoci\u00f3n, la conducta, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"content-sidebar","footnotes":""},"categories":[264,267,268],"tags":[],"class_list":["post-9744","post","type-post","status-publish","format-standard","has-post-thumbnail","category-emociones","category-cognicion","category-sensaciones-corporales","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mejorar los resultados en todas las terapias mediante la cognici\u00f3n y la emoci\u00f3n incorporadas<\/title>\n<meta name=\"description\" content=\"Investigaci\u00f3n que cambia paradigmas en neurociencia cognitiva en \u00e1reas llamadas cognici\u00f3n incorporada e incorporada e investigaci\u00f3n igualmente importante sobre los llamados enfoques incorporados y enactivos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mejorar los resultados en todas las terapias mediante la cognici\u00f3n y la emoci\u00f3n incorporadas\" \/>\n<meta property=\"og:description\" content=\"Investigaci\u00f3n que cambia paradigmas en neurociencia cognitiva en \u00e1reas llamadas cognici\u00f3n incorporada e incorporada e investigaci\u00f3n igualmente importante sobre los llamados enfoques incorporados y enactivos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/\" \/>\n<meta property=\"og:site_name\" content=\"ISP\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-16T08:25:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-16T08:30:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/02\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raja Selvam, PhD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raja Selvam, PhD\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/\"},\"author\":{\"name\":\"Raja Selvam, PhD\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#\\\/schema\\\/person\\\/bddf9014a05428d7831a82f46831693c\"},\"headline\":\"La ciencia de la cognici\u00f3n corporizada y la emoci\u00f3n enactiva: Implicaciones para mejorar los resultados en todas las terapias\",\"datePublished\":\"2024-05-16T08:25:42+00:00\",\"dateModified\":\"2024-05-16T08:30:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/\"},\"wordCount\":2919,\"image\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg\",\"articleSection\":[\"Emociones\",\"Cognici\u00f3n\",\"Sensaciones corporales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/\",\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/\",\"name\":\"Mejorar los resultados en todas las terapias mediante la cognici\u00f3n y la emoci\u00f3n incorporadas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg\",\"datePublished\":\"2024-05-16T08:25:42+00:00\",\"dateModified\":\"2024-05-16T08:30:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#\\\/schema\\\/person\\\/bddf9014a05428d7831a82f46831693c\"},\"description\":\"Investigaci\u00f3n que cambia paradigmas en neurociencia cognitiva en \u00e1reas llamadas cognici\u00f3n incorporada e incorporada e investigaci\u00f3n igualmente importante sobre los llamados enfoques incorporados y enactivos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg\",\"contentUrl\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg\",\"width\":750,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ciencia de la cognici\u00f3n corporizada y la emoci\u00f3n enactiva: Implicaciones para mejorar los resultados en todas las terapias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/\",\"name\":\"ISP\",\"description\":\"Integral Somatic Psychology\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/it\\\/#\\\/schema\\\/person\\\/bddf9014a05428d7831a82f46831693c\",\"name\":\"Raja Selvam, PhD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-raja-selvam-phd-96x96.png\",\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-raja-selvam-phd-96x96.png\",\"contentUrl\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-raja-selvam-phd-96x96.png\",\"caption\":\"Raja Selvam, PhD\"},\"url\":\"https:\\\/\\\/integralsomaticpsychology.com\\\/es\\\/author\\\/amsolutions\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mejorar los resultados en todas las terapias mediante la cognici\u00f3n y la emoci\u00f3n incorporadas","description":"Investigaci\u00f3n que cambia paradigmas en neurociencia cognitiva en \u00e1reas llamadas cognici\u00f3n incorporada e incorporada e investigaci\u00f3n igualmente importante sobre los llamados enfoques incorporados y enactivos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Mejorar los resultados en todas las terapias mediante la cognici\u00f3n y la emoci\u00f3n incorporadas","og_description":"Investigaci\u00f3n que cambia paradigmas en neurociencia cognitiva en \u00e1reas llamadas cognici\u00f3n incorporada e incorporada e investigaci\u00f3n igualmente importante sobre los llamados enfoques incorporados y enactivos.","og_url":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/","og_site_name":"ISP","article_published_time":"2024-05-16T08:25:42+00:00","article_modified_time":"2024-05-16T08:30:53+00:00","og_image":[{"width":750,"height":300,"url":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/02\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg","type":"image\/jpeg"}],"author":"Raja Selvam, PhD","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Raja Selvam, PhD","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/#article","isPartOf":{"@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/"},"author":{"name":"Raja Selvam, PhD","@id":"https:\/\/integralsomaticpsychology.com\/it\/#\/schema\/person\/bddf9014a05428d7831a82f46831693c"},"headline":"La ciencia de la cognici\u00f3n corporizada y la emoci\u00f3n enactiva: Implicaciones para mejorar los resultados en todas las terapias","datePublished":"2024-05-16T08:25:42+00:00","dateModified":"2024-05-16T08:30:53+00:00","mainEntityOfPage":{"@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/"},"wordCount":2919,"image":{"@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/#primaryimage"},"thumbnailUrl":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/02\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg","articleSection":["Emociones","Cognici\u00f3n","Sensaciones corporales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/","url":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/","name":"Mejorar los resultados en todas las terapias mediante la cognici\u00f3n y la emoci\u00f3n incorporadas","isPartOf":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/#primaryimage"},"image":{"@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/#primaryimage"},"thumbnailUrl":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/02\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg","datePublished":"2024-05-16T08:25:42+00:00","dateModified":"2024-05-16T08:30:53+00:00","author":{"@id":"https:\/\/integralsomaticpsychology.com\/it\/#\/schema\/person\/bddf9014a05428d7831a82f46831693c"},"description":"Investigaci\u00f3n que cambia paradigmas en neurociencia cognitiva en \u00e1reas llamadas cognici\u00f3n incorporada e incorporada e investigaci\u00f3n igualmente importante sobre los llamados enfoques incorporados y enactivos.","breadcrumb":{"@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/#primaryimage","url":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/02\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg","contentUrl":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2018\/02\/embodied-cognition-ISP-blog-raja-selvam-phd.jpg","width":750,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/integralsomaticpsychology.com\/es\/la-ciencia-de-la-cognicion-corporizada-y-la-emocion-enactiva-implicaciones-para-mejorar-los-resultados-en-todas-las-terapias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/integralsomaticpsychology.com\/"},{"@type":"ListItem","position":2,"name":"La ciencia de la cognici\u00f3n corporizada y la emoci\u00f3n enactiva: Implicaciones para mejorar los resultados en todas las terapias"}]},{"@type":"WebSite","@id":"https:\/\/integralsomaticpsychology.com\/it\/#website","url":"https:\/\/integralsomaticpsychology.com\/it\/","name":"ISP","description":"Integral Somatic Psychology","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/integralsomaticpsychology.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/integralsomaticpsychology.com\/it\/#\/schema\/person\/bddf9014a05428d7831a82f46831693c","name":"Raja Selvam, PhD","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2023\/10\/cropped-raja-selvam-phd-96x96.png","url":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2023\/10\/cropped-raja-selvam-phd-96x96.png","contentUrl":"https:\/\/integralsomaticpsychology.com\/wp-content\/uploads\/2023\/10\/cropped-raja-selvam-phd-96x96.png","caption":"Raja Selvam, PhD"},"url":"https:\/\/integralsomaticpsychology.com\/es\/author\/amsolutions\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/comments?post=9744"}],"version-history":[{"count":0,"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/media\/9745"}],"wp:attachment":[{"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/media?parent=9744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/categories?post=9744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/integralsomaticpsychology.com\/es\/wp-json\/wp\/v2\/tags?post=9744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}